{"id":2114,"date":"2021-03-31T00:00:00","date_gmt":"2021-03-30T22:00:00","guid":{"rendered":"https:\/\/floxik.de\/magazin\/2021\/03\/31\/silberner-labrador\/"},"modified":"2024-08-08T16:27:54","modified_gmt":"2024-08-08T14:27:54","slug":"silberner-labrador","status":"publish","type":"post","link":"https:\/\/floxik.de\/magazin\/hunderassen\/silberner-labrador\/","title":{"rendered":"Silberner Labrador"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Den <a href=\"https:\/\/floxik.de\/magazin\/hunderassen\/der-labrador\/\">Labrador<\/a> kennen wir alle. Aber vom silbernen Labrador haben viele sicherlich noch nicht geh\u00f6rt. Dabei k\u00f6nnte man sagen, dass es sich um den Zwillingsbruder des \u201enormalen\u201c Labradors handelt, nur dass er ein silbernes Fell tr\u00e4gt. <\/p><div id=\"floxi-1722291590\" class=\"floxi-chatbot floxi-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\">    <iframe\r\n      data-chat-frame=\"11ef639c-7b4d-f7d0-8a5a-d790f206031e\"\r\n      width=\"550\"\r\n      height=\"700\"\r\n      style=\"border:0;background:white;border: 1px solid lightgrey;border-radius: 10px;padding:15px;\"\r\n\t\t\t\r\n    ><\/iframe>\r\n    <script\r\n      src=\"https:\/\/retune.so\/api\/script\/chat.js?iframe&id=11ef639c-7b4d-f7d0-8a5a-d790f206031e\"\r\n      defer\r\n    ><\/script>\r\n    <\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Und genau dies ist seine Besonderheit. Aber nat\u00fcrlich ist er auch ein Hund, der fantastische F\u00e4higkeiten mit sich bringt und bestimmte Anforderungen an seinen Besitzer stellt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Charakter des Silbernen Labrador<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die oberste Pr\u00e4misse des Labradors ist, dass er seinem Herrchen, seiner Familie gefallen m\u00f6chte. Aus diesem Grunde setzt er eifrig seine intellektuellen und k\u00f6rperlichen F\u00e4higkeiten ein, um den aufgetragenen Lektionen folgen zu k\u00f6nnen. <\/p>\n\n\n\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-id=\"B01MSHEXVC\" data-aawp-product-title=\"FABCARE Laser Hornhautraspel Set  5-teilig  Neue verbesserte Version Austauschbare Raspelfl\u00e4che - Hornhautentferner inkl Mini Fu\u00dffeile Fu\u00dfpflege Set zur Hornhaut Entfernung Hornhautfeile\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\"\n           href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"&#128680; Silberne Labradore in Gefahr!\" rel=\"nofollow\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/07\/Hund-200g-Dosen_w960_h960_q90_jpg.jpg\" loading=\"lazy\" alt=\"&#128680; Silberne Labradore in Gefahr!\"  \/>\n        <\/a>\n\n                    <div class=\"aawp-product__rating\">\n                <a class=\"aawp-star-rating aawp-star-rating--medium aawp-star-rating--v2\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"Bewertungen auf Amazon\" rel=\"nofollow\" target=\"_blank\"><span style=\"width: 100%;\"><\/span><\/a>\n                            <\/div>\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"&#128680; Silberne Labradore in Gefahr!\" rel=\"nofollow\" target=\"_blank\">\n            &#128680; Silberne Labradore in Gefahr!        <\/a>\n        <div class=\"aawp-product__description\">\n            <b>&#128561; Erschreckende Fakten \u00fcber die Ern\u00e4hrung<br \/>&#9888;&#65039; 4 von 5 Labis leiden unter Mangelerscheinungen<br \/>&#128561; So verhinderst du schwerwiegende Folgen<\/p>\n<p><\/b>Achtung, Labradorbesitzer aufgepasst! &#128227; Die meisten handels\u00fcblichen Futtersorten sind eine tickende Zeitbombe &#128163; f\u00fcr die Gesundheit eurer silbernen Lieblinge. Gl\u00fccklichweise gibt es jetzt die ultimative Geheimwaffe: ANIFIT Nassfutter! &#128170; Vollgepackt mit besten Zutaten f\u00fcr maximale Power und einen umwerfenden Look. Tausende Labradore erstrahlen bereits in neuem Glanz - und das in Rekordzeit!<\/p>\n<p><b>&#128293; Exklusives Angebot: Spare 10% mit dem Code LEX10<br \/> &#128073; Nur solange der Vorrat reicht. Sei schneller als die anderen!<\/b>        <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\">ab 31,40 \u20ac<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--blue rounded shadow\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"Probierpaket Anifit anfordern \u00bb\" target=\"_blank\" rel=\"nofollow\">Probierpaket Anifit anfordern \u00bb<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n\n\n\n\n<p class=\"wp-block-paragraph\">Er m\u00f6chte sowohl die Aufgaben erf\u00fcllen, als auch der \u201eliebste Freund\u201c seiner Familie sein. Manchmal ist es schwierig, beide F\u00e4higkeiten unter einen Hut zu bekommen. Doch egal, wie engagiert er sich seiner Lektion gerade zeigt, dem Menschen gegen\u00fcber zeigt er sich immer freundlich und zugewandt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wer vergisst, dem Labrador seine t\u00e4glichen Streicheleinheiten zu kommen zulassen, wird feststellen, dass er vehement auf dieses \u201eFehlverhalten\u201c aufmerksam gemacht wird. Denn die Streicheleinheiten sind f\u00fcr den Hund nicht nur Balsam f\u00fcr die Seele. Sie sind f\u00fcr ihn ein wahres Lebenselexier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der geschichtliche Hintergrund des Silbernen Labrador<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die genaue Herkunft des Labradors ist bis heute nicht zu 100% gekl\u00e4rt. Der Ursprung wird in Portugal oder England vermutet. Von dort aus fand er seinen Weg nach Kanada, um genau zu sein, nach Neufundland. <\/p><div id=\"floxi-3953134965\" class=\"floxi-inhalt floxi-entity-placement\">\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-id=\"B01MSHEXVC\" data-aawp-product-title=\"FABCARE Laser Hornhautraspel Set  5-teilig  Neue verbesserte Version Austauschbare Raspelfl\u00e4che - Hornhautentferner inkl Mini Fu\u00dffeile Fu\u00dfpflege Set zur Hornhaut Entfernung Hornhautfeile\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\"\n           href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"UNSER TIPP: ANIFIT Nassfutter\" rel=\"nofollow\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/07\/Hund-200g-Dosen_w960_h960_q90_jpg.jpg\" alt=\"UNSER TIPP: ANIFIT Nassfutter\"  \/>\n        <\/a>\n\n                    <div class=\"aawp-product__rating\">\n                <a class=\"aawp-star-rating aawp-star-rating--medium aawp-star-rating--v2\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"Bewertungen auf Amazon\" rel=\"nofollow\" target=\"_blank\"><span style=\"width: 100%;\"><\/span><\/a>\n                            <\/div>\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"UNSER TIPP: ANIFIT Nassfutter\" rel=\"nofollow\" target=\"_blank\">\n            UNSER TIPP: ANIFIT Nassfutter         <\/a>\n        <div class=\"aawp-product__description\">\n            <b>\u25b7 Hoher Fleischanteil<br>\r\n\u25b7 Premium-Qualit\u00e4t der Zutaten <br>\r\n\u25b7 Frei von Tierversuchen <br>\r\n<br><\/b>\r\nANIFIT Nassfutter f\u00fcr Hunde ist ein hochwertiges Futter mit einem hohen Fleischanteil und Zutaten in Premium-Qualit\u00e4t. Es ist frei von k\u00fcnstlichen Zusatzstoffen und wird ohne Tierversuche hergestellt, was es zu einer gesunden und ethischen Wahl f\u00fcr die Ern\u00e4hrung Ihres Hundes macht.\r\n<br><br><b>10% F\u00dcR NEUKUNDEN<br>\r\n\u27a5 Gutscheincode: LEX10<br><\/b>\r\n        <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\">ab 31,40 \u20ac<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--blue rounded shadow\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"Probierpaket Anifit anfordern \u00bb\" target=\"_blank\" rel=\"nofollow\">Probierpaket Anifit anfordern \u00bb<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Hervorgehend aus den Molossern wurde er dort insbesondere von den Fischern und J\u00e4gern der Feuchtgebiete zum Apportieren eingesetzt. Es folgten im Laufe der Zeit weitere Einkreuzungen, um ihm in seiner Arbeit effektiver hervorbringen zu k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In den 1980er Jahren begannen Z\u00fcchter, die Farbgebung zu ver\u00e4ndern, um ihn insbesondere f\u00fcr das Vorf\u00fchren auf Hundeshows attraktiver zu machen. \u00dcber etwaige Folgen, die diese Genmanipulation mit sich bringen, hat sich niemand Gedanken gemacht. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denn in der Z\u00fcchtung haben sich zwei \u00c4ste entwickelt: Der Zweig, der sich auf das Ausstellen der Hunde konzentriert hat, sowie der zweite Zweig, der sich mit der Zucht der Jagdhunde befasst. Die heutigen Familienhunde gehen aus beiden Zuchtzweigen hervor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sicherlich gibt es auch heute noch viele Labradore unter den Ausstellungs- und Show-Hunden. Die Mehrheit der Hunde dieser Rasse jedoch ist als Gebrauchs- bzw. Familienhund bei ihren Menschen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Farben des Silbernen Labrador<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wie man es bereits dem Namen entnehmen kann, ist das Fell dieses Labradors nicht schwarz oder schwarz-braun, sondern silbern. Obwohl dies eigentlich auch nicht ganz korrekt beschrieben ist. Denn genau genommen besitzt auch der Silberne Labrador ein braunes Fell. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund einer gezielten Z\u00fcchtung aber, die in den USA ihren Anfang nahm, wurde die braune Farbe verd\u00fcnnt, wodurch sie silberne schimmerte. Dies erreichte man durch die Einkreuzung Dilute-Gens. Es sorgt daf\u00fcr, dass die Pigment-K\u00f6rnchen im Fell verklumpen und somit die Farbpigmente der braunen Farbe nicht mehr bis in die Spitzen und Oberfl\u00e4chen gelangen konnten. Man nennt dies ein rezessiv vererbtes Gen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Man sollte hinzuf\u00fcgen, dass das Dilute Gen nicht nur bei braunen Labradoren eingesetzt wurde. Auch bei schwarzen kam es zum Einsatz und brachte den so genannten Charcoal Labrador, also den \u201ekohlefarbenen\u201c Labrador. Bei den gelben Labradoren verzeichnen wir den champagnerfarbenen Labrador, dessen F\u00e4rbung auch auf das Dilute Gen zur\u00fcckgeht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grunds\u00e4tzlich handelt es sich um einen kurzhaarigen Hund, der entsprechend leicht zu pflegen ist. Meist gen\u00fcgt es, den groben Schmutz mit der Hand herauszustreichen oder hierf\u00fcr eine mittelgrobe B\u00fcrste zu verwenden. Wasser und Shampoo werden so gut wie gar nicht ben\u00f6tigt. Dennoch ist das Fell sehr dicht und somit auch im Winter ein guter Schutz vor K\u00e4lte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die genannten Sonderfarben werden vom FCI \u00fcbrigens nicht anerkannt. Als Grund hierf\u00fcr werden die gesundheitlichen Probleme genannt, die mit der Einkreuzung des Dilute Gens einhergehen. Hierzu sp\u00e4ter.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Welche Anspr\u00fcche stellt der Silberne Labrador?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Als ehemaliger Jagdhund ben\u00f6tigt der silberne Labrador auch heute noch ausreichend t\u00e4glichen Auslauf. Dieser kann sich als lange Spazierg\u00e4nge, am Fahrrad, \u00dcbungseinheit auf dem Hundesportplatz, aber Badeeinheiten im nahegelegenen See oder Fluss entpuppen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr den Labrador ist es generell wichtig, dass er nur selten, und wenn dann nur f\u00fcr kurze Zeitr\u00e4ume, allein gelassen wird. Wird er zu oft und zu lange alleine gelassen, kann es ihm zur Gewohnheit werden, sich ungeb\u00fcrtig zu benehmen, etwa lautes, dauerhaftes Jaulen oder Bellen, aber auch psychische Probleme zu entwickeln. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sicherlich kann auch diese Lektion ge\u00fcbt und entsprechend ausgeweitet werden. Anf\u00e4nglich jedoch sollte eine lange Abwesenheit vermieden werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund seiner Intelligenz sollte der silberne Labrador nicht nur k\u00f6rperlich, sondern auch geistig gef\u00f6rdert werden. Hier eignen sich Such- und Schnupperspiele f\u00fcr den Anfang. Sp\u00e4ter kann man dann unter anderem zum Mantrailing \u00fcbergehen. Aber nat\u00fcrlich ist er eigentlich f\u00fcr jede k\u00f6rperliche und geistige Herausforderung offen. Hauptsache, er kann mit \u201eseinen Menschen\u201c zusammensein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der Silberne Labrador und seine Gesundheit<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es besteht beim silbernen Labrador eine erh\u00f6hte Wahrscheinlichkeit, dass das Tier an der Hautkrankheit \u201eCDA\u201c, Colour delution alopecia, erkrankt. Hierbei handelt es sich um eine wirklich ernste Krankheit. In ihrem Verlauf kommt es unter anderem zu Nierenproblemen unterschiedlicher Genese, aber auch Hautekzemen und vor allem Juckreiz. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In vielen F\u00e4llen ist die CDA erstmalig bereits zwischen dem 1. und dem 2. Lebensjahr zu verzeichnen. Diese Erkrankung f\u00fchrt zu einem Dauerstress der betroffenen Hunde. In den meisten F\u00e4llen ist nur eine einigerma\u00dfen wirksame Behandlung mit Antibiotika m\u00f6glich. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund der Tatsache, dass es sich um die Folgen der genetischen Ver\u00e4nderung des Erbgutes handelt, ist die CDA nicht heilbar. Sie kann nur bedingt gemildert werden. Dies gilt leider auch f\u00fcr die naturheilkundlichen Therapiemethoden. <\/p>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"background-color:#fefad8\"><strong>ABER: <\/strong>Nat\u00fcrlich ist nicht jeder silberne Labrador von der CDA tats\u00e4chlich betroffen. Es sollte diesbez\u00fcglich auf eine m\u00f6glichst \u201efreie\u201c Zuchtlinie geachtet werden. Das bedeutet, dass es sich um eine Zuchtlinie handelt, bei der diese Erkrankungen (bisher) nicht zum Vorschein getreten ist. Dennoch sollte jeder Besitzer eines silbernen Labradors die Zeichen erkennen k\u00f6nnen, um schnell handeln zu k\u00f6nnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vor- und Nachteile des Silbernen Labrador<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Hund wird von jedem geliebt. Man kann n\u00e4mlich gar nicht anders. Er ist sehr leicht zu pflegen, da Schmutz wie von alleine aus seinem Fell herausf\u00e4llt. Aufgrund seiner Intelligenz und seinem Willen zu lernen und dem Menschen zu gefallen, ist es recht einfach, ihn zu erziehen und auszubilden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daher eignet er sich nicht nur bestens als Familienhund, sondern auch als Therapie-, Schul- und Begleithund. Auch die Ausbildung zum Rettungshund oder \u201eSchn\u00fcffler\u201c bei Polizei und Zoll ist durchaus denkbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund seiner Gelehrigkeit, aber auch dem starken Wunsch, seinem Herrchen zu gefallen, kann dieser Hund, mit der versierten Unterst\u00fctzung einer Hundeschule, auch von einem Anf\u00e4nger gut erzogen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So sch\u00f6n das silberne Fell auch ist, sollte stets daran gedacht werden, dass aufgrund der Genmanipulation eine Tendenz zu Nierenproblemen, Ekzemen der Haut sowie Juckreiz bestehen kann. Um rechtzeitig einschreiten zu k\u00f6nnen, ist es wichtig, sich mit dem Symptomenkomplex des CDA auseinanderzusetzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der perfekte Mensch f\u00fcr einen Silbernen Labrador<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bewegt sich gerne im Freien, in der Natur, auf dem Hundesportplatz<\/li>\n\n\n\n<li>Kann dem Hund einen Garten bieten<\/li>\n\n\n\n<li>Mag es, wenn der Hund ein Familienmitglied und damit der geheime Mittelpunkt der Familie ist<\/li>\n\n\n\n<li>Liebt das Zusammenspiel von Hund und Mensch in allen Lebenslagen<\/li>\n\n\n\n<li>Liebt es, sich voll und ganz auf seinen Hund verlassen zu k\u00f6nnen, wenn dieser seine Ausbildung beendet hat<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Die Welpen des Silbernen Labrador kaufen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In der heutigen Zeit ist es wichtiger denn je, sich nach einem seri\u00f6sen Z\u00fcchter, der m\u00f6glichst nach FCI-Standards seine Zucht betreibt, zu finden, wenn man einen Welpen des silbernen Labradors kaufen m\u00f6chte. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der \u201eHundemarkt\u201c ist leergefegt, da viele Menschen, viele Familien aufgrund der Corona-Situation mit einem Zeit haben, sich um Hunde zu k\u00fcmmern. Damit hat sich aber auch der Markt f\u00fcr unseri\u00f6se Z\u00fcchter und Vermehrer ge\u00f6ffnet, die ihre Zucht auf zwielichtige Weise und selten unter Beachtung des Tierschutzes betreiben. Von diesen Z\u00fcchtern sollten Sie sich fernhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lassen Sie sich vom Z\u00fcchter die Unterlagen der Zuchtlinie zeigen. Seri\u00f6se Vertreter tun dies nur allzu gerne. Stellen Sie Fragen \u00fcber die Elterntiere, die Pr\u00e4gungsphase beim Z\u00fcchter in den ersten Wochen und die Untersuchungen und Impfungen, die die Tiere durchlaufen. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador-welpe.jpg\" loading=\"lazy\" alt=\"Silberner Labrador Welpe\" class=\"wp-image-10529\"\/><figcaption class=\"wp-element-caption\">Silberner Labrador Welpe | Foto: SandraFotodesign \/ Depositphotos.com<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbernehmen Sie nur einen Hund, der mit geordneten Papieren und vollst\u00e4ndigen Untersuchungen \/ Impfungen \u00fcbergeben werden soll. Zudem sollten mehrere Kennenlernbesuche m\u00f6glich sein, damit Hund und neues Herrchen \/ Familie sich bereits kennenlernen k\u00f6nnen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seien Sie zum Wohle der Hunde ein nerviger Interessent, der sich f\u00fcr die Tiere interessiert und dem Z\u00fcchter gleichzeitig ausreichend Zeit gibt, um die Tiere bis mindestens zur 12 Lebenswoche betreuen und auf ihr kommendes Leben vorzubereiten. Sie werden sehen, dass sich dieses Vorgehen bezahlt macht und nur positive Folgen mit sich bringt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Erste Ausstattung f\u00fcr den Silbernen Labrador<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/hundehalsband\/\">Hundehalsband<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/hundegeschirr\/\">Hundegeschirr<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/floxik.de\/magazin\/ratgeber\/welche-hundeleine-passt-zu-welchem-zweck\/\">Hundeleine<\/a>, zus\u00e4tzlich eventuelle eine <a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/schleppleine\/\">Schleppleine<\/a><\/li>\n\n\n\n<li>Wasser- und Futternapf, m\u00f6glichst leicht zu reinigen<\/li>\n\n\n\n<li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/hundebett\/\">Hundebett<\/a> \/ Decke f\u00fcr den Liegeplatz<\/li>\n\n\n\n<li>Langhaarb\u00fcrste<\/li>\n\n\n\n<li>Unterwolle-B\u00fcrste<\/li>\n\n\n\n<li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/hundekamm\/\">Hundekamm<\/a> \/ L\u00e4usekamm<\/li>\n\n\n\n<li>Hundefutter<\/li>\n\n\n\n<li>eventuell Spielzeug<\/li>\n\n\n\n<li>eventuell Leckerlis<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Hundefutter f\u00fcr den Silbernen Labrador<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der silberne Labrador ben\u00f6tigt eine ausgewogene Kost. Ob es sich hierbei jedoch um frisches, selbstgekochtes oder selbstgekauftes Futter handelt, ist unerheblich. Nur die Qualit\u00e4t und die Menge sind entscheidend. Ist der Hund nicht ausreichend ausgelastet, ist die Menge m\u00f6glichst sofort zu reduzieren, da er ansonsten schnell an Gewicht zunimmt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fazit<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der silberne Labrador ist ein eher seltener Vertreter dieser Rasse, kommt aber mit den gleichen, faszinierenden Eigenschaften des Labradors an sich daher. Somit ist er ein toller Familien-, Schul-, Therapie- und Begleithund, str\u00e4ubt sich aber auch nicht gegen die Ausbildung zum Rettungs- oder Jagdhund. Alles in allem ist er ein fantastischer \u201eAllrounder\u201c, den man nur lieben kann.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">FAQ<\/h2>\n\n\n\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Wie viel kostet ein Silberner Labrador?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"has-large-font-size wp-block-paragraph\">Die Frage um den Preis ist aktuell (Stand 03\/2021) nicht einfach zu beantworten. F\u00fcr gew\u00f6hnlich liegt der Preis f\u00fcr einen silbernen Labrador zwischen EURO 1.500 und EURO 2.500. <br><br>Aktuell ist die Nachfrage nach Hunden allerdings grunds\u00e4tzlich, was die Preise f\u00fcr einen Welpen ganz allgemein in horrende H\u00f6hen treibt. So kann es durchaus vorkommen, dass aktuell Preise von EURO 3.500 und mehr f\u00fcr einen silbernen Labrador verlangt werden. <br><br>Wichtig ist dabei aber nicht nur der Preis: Schauen Sie sich den Z\u00fcchter und seine Referenzen genau an. Es besteht aktuell akut die Gefahr, an einen so genannten Vermehrer zu geraten, der seine Zuchth\u00fcndinnen ausnutzt, weder ihre noch die Gesundheit der Welpen beachtet und \u00e4hnliches. Damit tut man weder sich noch den beteiligten Tieren tats\u00e4chlich einen Gefallen.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Woher kommt der Silberne Labrador?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"has-large-font-size wp-block-paragraph\">Die Herkunft des Labradors liegt in Neufundland, eines kanadischen Bundesstaates. Jedoch wird vermutet, dass seine Vorfahren aus England und \/ oder Portugal stammen.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Wie alt wird der Silberne Labrador?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"has-large-font-size wp-block-paragraph\">Wie bereits erw\u00e4hnt geh\u00f6rt der silberne Labrador eigentlich zu den braunen Labradoren. Diese haben, im Gegensatz zum schwarzen Labrador, eine k\u00fcrzere Lebenserwartung. Sie werden meist \u201enur\u201c ungef\u00e4hr 10,5 Jahre alt. Dies ist rund 2 Jahre weniger, als alle andersfarbigen Labradore aufweisen. Als Zugeh\u00f6riger der Farbe Braun ist auch beim silbernen Labrador mit dieser Lebenserwartung zu rechnen.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Wie gro\u00df und schwer wird der Silberne Labrador?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"has-large-font-size wp-block-paragraph\">Bei den R\u00fcden ist eine Schulterh\u00f6he von 56 bis 57 Zentimetern und ein Gewicht von 29 bis 36 Kilogramm zu verzeichnen. Die H\u00fcndinnen sind nur geringf\u00fcgig kleiner und leichter: 55 Zentimeter und 25 bis 32 Kilogramm.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Wie viele Welpen bekommt der Silberne Labrador?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"has-large-font-size wp-block-paragraph\">Der durchschnittliche Wurf des silbernen Labradors umfasst 5 bis 7 Welpen. In seltenen F\u00e4llen kommt es bis zu einer Wurfgr\u00f6\u00dfe von 10 Welpen.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Ist der Silberne Labrador ein Jagdhund?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"has-large-font-size wp-block-paragraph\">Um diese Frage beantworten zu k\u00f6nnen, muss man ein kleines bisschen weiter ausholen. Denn der Labrador ist heute kein klassischer Jagdhund mehr. Vielmehr geht er aus den Molossern hervor und wurde urspr\u00fcnglich f\u00fcr die Jagd am und im Wasser gezogen. Insbesondere zum Apportieren wurde er dort, sp\u00e4ter aber auch von den J\u00e4gern am Land eingesetzt. Da die moderneren Schusswaffen daf\u00fcr sorgten, dass der Labrador auch weiter entfernt gefallene Wasserv\u00f6gel apportieren musste, kreuzte man andere Jagdhundrassen ein. Noch heute kann ein Labrador zu einem guten Jagdhund ausgebildet werden. Allerdings ist die Nachfrage auf diesem Sektor nicht mehr so gro\u00df wie fr\u00fcher.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Ist der Silberne Labrador ein Familienhund?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"has-large-font-size wp-block-paragraph\">Der silberne Labrador ist, wie alle Labradore, ein nahezu perfekter Familienhund. Er ist nicht sch\u00fcchtern, mag gerne gestreichelt und \u201eangefasst\u201c werden. Dabei ist er sehr geduldig und hegt und pflegt den Nachwuchs der Familie, egal welchen Alters. Auch um die Senioren mag er sich gerne k\u00fcmmern. Die Familie sollte allerdings, um ihm tats\u00e4chlich gerecht werden zu k\u00f6nnen, bewegungsfreudig sein. Denn er ben\u00f6tigt nicht nur das Spiel mit den Kindern oder im Garten, sondern lange Spazierg\u00e4nge oder eine entsprechende Herausforderung auf dem Hundesportplatz.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Kann der Silberne Labrador in einer (Stadt-)wohnung gehalten werden?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"wp-block-paragraph\">Um seiner Familie, seinem Besitzer zu gefallen, w\u00fcrde sich der Labrador auch in einer gro\u00dfz\u00fcgig geschnittenen Wohnung wohlf\u00fchlen k\u00f6nnen. Allerdings m\u00fcssten die Gegebenheiten geschaffen werden, um seinem Bewegungsdrang nachkommen zu k\u00f6nnen. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ist er k\u00f6rperlich und geistig nicht ausgelastet, kann es durchaus zu Zwangshandlungen kommen, die nicht nur den Hund, sondern auch die Nachbarn belasten w\u00fcrden. Eine Wohnung mit angrenzendem Garten jedoch w\u00e4re ein sehr guter Kompromiss. Den k\u00f6rperlichen Ausgleich braucht er nat\u00fcrlich dennoch.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Besitzt der silberne Labrador eine gute Gesundheit?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"has-large-font-size wp-block-paragraph\">Seine spezielle Fellfarbe erlangt er durch eine Genmutation. Diese f\u00fchrt leider dazu, dass er zu Hauterkrankungen mit und ohne Juckreiz sowie Nierenproblemen neigt. Diese Erkrankungen k\u00f6nnen zu Tage treten, m\u00fcssen aber nicht.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Ist der silberne Labrador leichtf\u00fcttrig?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"has-large-font-size wp-block-paragraph\">Grunds\u00e4tzlich ist er kein Kostver\u00e4chter, sodass man mit der Futtermenge Ma\u00df halten sollte. Dennoch ist auf die Qualit\u00e4t des Futters zu achten. Das BARFEN w\u00e4re eine gute Option, aber nat\u00fcrlich akzeptiert er auch Trocken- und Na\u00dffutter.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\n<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\": \"FAQPage\",\n\t\t\"mainEntity\": [\n\t\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Wie viel kostet ein Silberner Labrador?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Die Frage um den Preis ist aktuell (Stand 03\/2021) nicht einfach zu beantworten. F\u00fcr gew\u00f6hnlich liegt der Preis f\u00fcr einen silbernen Labrador zwischen EURO 1.500 und EURO 2.500. <br><br>Aktuell ist die Nachfrage nach Hunden allerdings grunds\u00e4tzlich, was die Preise f\u00fcr einen Welpen ganz allgemein in horrende H\u00f6hen treibt. So kann es durchaus vorkommen, dass aktuell Preise von EURO 3.500 und mehr f\u00fcr einen silbernen Labrador verlangt werden. <br><br>Wichtig ist dabei aber nicht nur der Preis: Schauen Sie sich den Z\u00fcchter und seine Referenzen genau an. Es besteht aktuell akut die Gefahr, an einen so genannten Vermehrer zu geraten, der seine Zuchth\u00fcndinnen ausnutzt, weder ihre noch die Gesundheit der Welpen beachtet und \u00e4hnliches. Damit tut man weder sich noch den beteiligten Tieren tats\u00e4chlich einen Gefallen.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Woher kommt der Silberne Labrador?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Die Herkunft des Labradors liegt in Neufundland, eines kanadischen Bundesstaates. Jedoch wird vermutet, dass seine Vorfahren aus England und \/ oder Portugal stammen.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Wie alt wird der Silberne Labrador?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Wie bereits erw\u00e4hnt geh\u00f6rt der silberne Labrador eigentlich zu den braunen Labradoren. Diese haben, im Gegensatz zum schwarzen Labrador, eine k\u00fcrzere Lebenserwartung. Sie werden meist \u201enur\u201c ungef\u00e4hr 10,5 Jahre alt. Dies ist rund 2 Jahre weniger, als alle andersfarbigen Labradore aufweisen. Als Zugeh\u00f6riger der Farbe Braun ist auch beim silbernen Labrador mit dieser Lebenserwartung zu rechnen.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Wie gro\u00df und schwer wird der Silberne Labrador?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Bei den R\u00fcden ist eine Schulterh\u00f6he von 56 bis 57 Zentimetern und ein Gewicht von 29 bis 36 Kilogramm zu verzeichnen. Die H\u00fcndinnen sind nur geringf\u00fcgig kleiner und leichter: 55 Zentimeter und 25 bis 32 Kilogramm.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Wie viele Welpen bekommt der Silberne Labrador?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Der durchschnittliche Wurf des silbernen Labradors umfasst 5 bis 7 Welpen. In seltenen F\u00e4llen kommt es bis zu einer Wurfgr\u00f6\u00dfe von 10 Welpen.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Ist der Silberne Labrador ein Jagdhund?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Um diese Frage beantworten zu k\u00f6nnen, muss man ein kleines bisschen weiter ausholen. Denn der Labrador ist heute kein klassischer Jagdhund mehr. Vielmehr geht er aus den Molossern hervor und wurde urspr\u00fcnglich f\u00fcr die Jagd am und im Wasser gezogen. Insbesondere zum Apportieren wurde er dort, sp\u00e4ter aber auch von den J\u00e4gern am Land eingesetzt. Da die moderneren Schusswaffen daf\u00fcr sorgten, dass der Labrador auch weiter entfernt gefallene Wasserv\u00f6gel apportieren musste, kreuzte man andere Jagdhundrassen ein. Noch heute kann ein Labrador zu einem guten Jagdhund ausgebildet werden. Allerdings ist die Nachfrage auf diesem Sektor nicht mehr so gro\u00df wie fr\u00fcher.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Ist der Silberne Labrador ein Familienhund?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Der silberne Labrador ist, wie alle Labradore, ein nahezu perfekter Familienhund. Er ist nicht sch\u00fcchtern, mag gerne gestreichelt und \u201eangefasst\u201c werden. Dabei ist er sehr geduldig und hegt und pflegt den Nachwuchs der Familie, egal welchen Alters. Auch um die Senioren mag er sich gerne k\u00fcmmern. Die Familie sollte allerdings, um ihm tats\u00e4chlich gerecht werden zu k\u00f6nnen, bewegungsfreudig sein. Denn er ben\u00f6tigt nicht nur das Spiel mit den Kindern oder im Garten, sondern lange Spazierg\u00e4nge oder eine entsprechende Herausforderung auf dem Hundesportplatz.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Kann der Silberne Labrador in einer (Stadt-)wohnung gehalten werden?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Um seiner Familie, seinem Besitzer zu gefallen, w\u00fcrde sich der Labrador auch in einer gro\u00dfz\u00fcgig geschnittenen Wohnung wohlf\u00fchlen k\u00f6nnen. Allerdings m\u00fcssten die Gegebenheiten geschaffen werden, um seinem Bewegungsdrang nachkommen zu k\u00f6nnen. <br><\/p><p>Ist er k\u00f6rperlich und geistig nicht ausgelastet, kann es durchaus zu Zwangshandlungen kommen, die nicht nur den Hund, sondern auch die Nachbarn belasten w\u00fcrden. Eine Wohnung mit angrenzendem Garten jedoch w\u00e4re ein sehr guter Kompromiss. Den k\u00f6rperlichen Ausgleich braucht er nat\u00fcrlich dennoch.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Besitzt der silberne Labrador eine gute Gesundheit?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Seine spezielle Fellfarbe erlangt er durch eine Genmutation. Diese f\u00fchrt leider dazu, dass er zu Hauterkrankungen mit und ohne Juckreiz sowie Nierenproblemen neigt. Diese Erkrankungen k\u00f6nnen zu Tage treten, m\u00fcssen aber nicht.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Ist der silberne Labrador leichtf\u00fcttrig?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Grunds\u00e4tzlich ist er kein Kostver\u00e4chter, sodass man mit der Futtermenge Ma\u00df halten sollte. Dennoch ist auf die Qualit\u00e4t des Futters zu achten. Das BARFEN w\u00e4re eine gute Option, aber nat\u00fcrlich akzeptiert er auch Trocken- und Na\u00dffutter.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t\t\t\t]\n\t}\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Den Labrador kennen wir alle. Aber vom silbernen Labrador haben viele sicherlich noch nicht geh\u00f6rt. Dabei k\u00f6nnte man sagen, dass es sich um den Zwillingsbruder&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2117,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-2114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hunderassen"],"uagb_featured_image_src":{"full":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador.jpg",825,549,false],"thumbnail":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador-150x150.jpg",150,150,true],"medium":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador-300x200.jpg",300,200,true],"medium_large":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador-768x511.jpg",726,483,true],"large":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador.jpg",726,483,false],"1536x1536":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador.jpg",825,549,false],"2048x2048":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador.jpg",825,549,false],"epcl_classic":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador.jpg",660,439,false],"epcl_fullcover":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/silberner-labrador.jpg",825,549,false]},"uagb_author_info":{"display_name":"Floxik Redaktion","author_link":"https:\/\/floxik.de\/magazin\/author\/redaktion\/"},"uagb_comment_info":0,"uagb_excerpt":"Den Labrador kennen wir alle. Aber vom silbernen Labrador haben viele sicherlich noch nicht geh\u00f6rt. Dabei k\u00f6nnte man sagen, dass es sich um den Zwillingsbruder...","_links":{"self":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts\/2114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/comments?post=2114"}],"version-history":[{"count":2,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts\/2114\/revisions"}],"predecessor-version":[{"id":3632,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts\/2114\/revisions\/3632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/media\/2117"}],"wp:attachment":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/media?parent=2114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/categories?post=2114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/tags?post=2114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}