{"id":2464,"date":"2022-04-19T00:00:00","date_gmt":"2022-04-18T22:00:00","guid":{"rendered":"https:\/\/floxik.de\/magazin\/2022\/04\/19\/der-english-cocker-spaniel\/"},"modified":"2024-05-31T09:53:57","modified_gmt":"2024-05-31T07:53:57","slug":"der-english-cocker-spaniel","status":"publish","type":"post","link":"https:\/\/floxik.de\/magazin\/hunderassen\/der-english-cocker-spaniel\/","title":{"rendered":"Der English Cocker Spaniel"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der English Cocker Spaniel ist uns allen ein Begriff, denn man sieht ihn vielerorts. Ein fr\u00f6hlicher Hund mit lustigen Schlappohren, der sich \u00fcber jeden Menschen freut, der ihm freundlich begegnet. Richtig, er hat eine Vergangenheit als Jagdhund. Doch ist er heute ein sehr beliebter Hund bei Jung und Alt. Aufgrund seines netten Wesens ist er einerseits ein Anf\u00e4ngerhund, andererseits ein perfekter Hund f\u00fcr die junge Familie mit Kindern. Wer sich zum allerersten Mal einen Hund anschaffen m\u00f6chte, ist mit dieser Hunderasse bestens beraten.<\/p><div id=\"floxi-1478131576\" class=\"floxi-chatbot floxi-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\">    <iframe\r\n      data-chat-frame=\"11ef639c-7b4d-f7d0-8a5a-d790f206031e\"\r\n      width=\"550\"\r\n      height=\"700\"\r\n      style=\"border:0;background:white;border: 1px solid lightgrey;border-radius: 10px;padding:15px;\"\r\n\t\t\t\r\n    ><\/iframe>\r\n    <script\r\n      src=\"https:\/\/retune.so\/api\/script\/chat.js?iframe&id=11ef639c-7b4d-f7d0-8a5a-d790f206031e\"\r\n      defer\r\n    ><\/script>\r\n    <\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Charakter des English Cocker Spaniel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Hund ist die perfekte Mischung aus einem Begleithund und einem <a href=\"https:\/\/floxik.de\/magazin\/hunderassen\/jagdhunde\/\"  >Jagdhund<\/a>. In keiner anderen Rasse hat sich diese Mischung, dieses Miteinandereinhergehen beider Komponenten, so fantastisch herauskristallisieren k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Cocker Spaniel ist aufgeschlossen, intelligent, fr\u00f6hlich, mutig, ausdauernd, wachsam und zugleich zuverl\u00e4ssig. Genau genommen scheint dieser Hund der perfekt Begleithund f\u00fcr den Menschen zu sein. Dieser sollte allerdings wissen, dass viele, lange Spazierg\u00e4nge auf ihn zukommen. Denn diese ben\u00f6tigt er f\u00fcr ein ausgeglichenes Wesen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der geschichtliche Hintergrund des English Cocker Spaniel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es gab einmal den \u201eCocker Spaniel\u201c. Aufgrund der Tatsache, dass sich in den USA eine Zuchtlinie abgespalten hat, das \u00fcberwiegend Showhunde hervorbrachte, wurde entschieden, dass der eigentliche Cocker Spaniel, der seine Herkunft in England findet, als \u201eEnglish Cocker Spaniel\u201c bezeichnet wird. In England hat er als Jagdhund eine ganz spezielle Aufgabe zu erledigen gehabt: Als so genannter St\u00f6berhund war es sein Job, das Wild zun\u00e4chst zu finden, also aufzust\u00f6bern, und aufzuschrecken. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es sollte auffliegen oder weglaufen. Zum einen ist es f\u00fcr den St\u00f6berhund wichtig, die richtige Entfernung zum J\u00e4ger einzuhalten, damit dieser die M\u00f6glichkeit hat, den bestm\u00f6glichen Schuss abzugeben. Zum anderen war es absolut notwendig, dass er nach dem Aufschrecken an Ort und Stelle verharrte. Er darf dem Wild auf keinen Fall nachsetzen, da er sonst Gefahr l\u00e4uft, selbst getroffen zu werden. Erst wenn der Schuss gefallen ist und darf er hinterhersetzen und das getroffene Wild apportieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Man mag sich dar\u00fcber wundern, dass dieser Hund ein derart komplexes Verhalten an den Tag legen kann. Und doch wird man feststellen k\u00f6nnen, dass der Hund seine Wurzeln bei den Kelten und Germanen findet. Allerdings ist die Form, das Erscheinungsbild, wie wir es heute kennen, erst seit gut 200 Jahre bekannt. Letztlich wurde diese Rasse im Jahr 1873 akzeptiert und mit dem noch g\u00fcltigen Standard versehen.<\/p><div id=\"floxi-3389831086\" class=\"floxi-inhalt floxi-entity-placement\">\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-id=\"B01MSHEXVC\" data-aawp-product-title=\"FABCARE Laser Hornhautraspel Set  5-teilig  Neue verbesserte Version Austauschbare Raspelfl\u00e4che - Hornhautentferner inkl Mini Fu\u00dffeile Fu\u00dfpflege Set zur Hornhaut Entfernung Hornhautfeile\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\"\n           href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"UNSER TIPP: ANIFIT Nassfutter\" rel=\"nofollow\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/07\/Hund-200g-Dosen_w960_h960_q90_jpg.jpg\" alt=\"UNSER TIPP: ANIFIT Nassfutter\"  \/>\n        <\/a>\n\n                    <div class=\"aawp-product__rating\">\n                <a class=\"aawp-star-rating aawp-star-rating--medium aawp-star-rating--v2\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"Bewertungen auf Amazon\" rel=\"nofollow\" target=\"_blank\"><span style=\"width: 100%;\"><\/span><\/a>\n                            <\/div>\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"UNSER TIPP: ANIFIT Nassfutter\" rel=\"nofollow\" target=\"_blank\">\n            UNSER TIPP: ANIFIT Nassfutter         <\/a>\n        <div class=\"aawp-product__description\">\n            <b>\u25b7 Hoher Fleischanteil<br>\r\n\u25b7 Premium-Qualit\u00e4t der Zutaten <br>\r\n\u25b7 Frei von Tierversuchen <br>\r\n<br><\/b>\r\nANIFIT Nassfutter f\u00fcr Hunde ist ein hochwertiges Futter mit einem hohen Fleischanteil und Zutaten in Premium-Qualit\u00e4t. Es ist frei von k\u00fcnstlichen Zusatzstoffen und wird ohne Tierversuche hergestellt, was es zu einer gesunden und ethischen Wahl f\u00fcr die Ern\u00e4hrung Ihres Hundes macht.\r\n<br><br><b>10% F\u00dcR NEUKUNDEN<br>\r\n\u27a5 Gutscheincode: LEX10<br><\/b>\r\n        <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\">ab 31,40 \u20ac<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--blue rounded shadow\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"Probierpaket Anifit anfordern \u00bb\" target=\"_blank\" rel=\"nofollow\">Probierpaket Anifit anfordern \u00bb<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Eines hat sich bei dem English Cocker Spaniel \u00fcbrigens nicht etabliert: Mixe. Nur selten tauchen Cocker-Mixe auf.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Farben des English Cocker Spaniel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Cocker Spaniel ist ein Hund, der viel Farben tragen kann. Er kann sowohl einfarbig als auch zwei- und dreifarbig auftreten: Schwarz, Braun, Rot, Leber (Schokobraun), aber auch Schwarz mit Loh und Braun mit Loh, zudem Orange-Wei\u00df, Schwarz-Wei\u00df, Lemon-Wei\u00df, Braun-Wei\u00df und letztlich Schwarz-Wei\u00df mit Loh und Braun-Wei\u00df mit Loh.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nat\u00fcrlich sind nicht alle Farben gleicherma\u00dfen vertreten. Gerade die seltenen Farbgebungen sind sehr beliebt und entsprechend teuer. Einfach jeder m\u00f6chte einen dieser sehr bunten Spaniel haben, sowohl die Z\u00fcchter als auch die \u201enormalen\u201c Besitzer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Fell des Spaniels will regelm\u00e4\u00dfig geb\u00fcrstet werden. Alle zwei Tage ist empfehlenswert. Wer allerdings die \u201eStandardfrisur\u201c des Cockers sehen m\u00f6chte, sollte den Hund regelm\u00e4\u00dfig trimmen bzw. zu diesem Zweck einen Hundefriseur aufsuchen. Dies ist aber nat\u00fcrlich nur dann notwendig, wenn Sie mit dem Hund zur Ausstellung oder auf eine Rasse-Pr\u00fcfung fahren m\u00f6chten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Welche Anspr\u00fcche stellt der English Cocker Spaniel?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Er m\u00f6chte akzeptiert und geliebt werden. Das bedeutet, dass er einerseits seinem Menschen gefallen m\u00f6chte. Auf der anderen Seite aber ben\u00f6tigt er auch die Aufmerksamkeit und starke, aber liebevolle F\u00fchrung. Er passt sich den Gegebenheiten an und wird dort zufrieden sein, wo seine Lieblingsmenschen leben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Bezug auf die Pflege und Gesundheit ist ein wenig Aufmerksamkeit notwendig, um die Ohren und Leftzen sauber und entz\u00fcndungsfrei zu halten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der English Cocker Spaniel und seine Gesundheit<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die \u00fcbergro\u00dfen Schlappohren des Hundes k\u00f6nnen leicht zu einem Problem werden. Deshalb m\u00fcssen sie regelm\u00e4\u00dfig \u00fcberpr\u00fcft und bei Bedarf gereinigt werden. Geschieht dies nicht, kann es schnell zu Entz\u00fcndungen im inneren wie auch dem \u00e4u\u00dferen Geh\u00f6rgang kommen. Leider ist bei unzureichender Pflege nicht auszuschlie\u00dfen, dass ein Ohrenzwang entsteht. Ein h\u00e4ufiges Bild sind Lefzen-Ekzeme. Auch in diesem Punkt hilft nur das h\u00e4ufige \u00dcberpr\u00fcfen und Reinlichkeit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zudem lassen sich die erblich bedingte Progressive-Retina-Atrophie sowie die Nephropathie feststellen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Cockerwut, ein nervlich bedingtes Leiden, tritt heute zum Gl\u00fcck nur noch selten auf. Sie zeigt sich als eine epilepsieartige Erkrankung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zwar ist es keine Erkrankung, doch ist stets auf ein gut getrimmtes Fell zu achten. Dies gilt insbesondere, wenn der Hund sich im Jagddienst befindet. Zu langes Haar, wie auch zu langer Ohrenbehang k\u00f6nnte den Hund sowohl beim Laufen als auch beim St\u00f6bern st\u00f6ren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vor- und Nachteile des English Cocker Spaniel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund seiner Vorgeschichte als Jagdhund kann man sich bereits denken, dass der Cocker Spaniel viel Bewegung ben\u00f6tigt. Dies muss von Anfang an klar sein, denn zwei bis drei gr\u00f6\u00dfere<a href=\"https:\/\/floxik.de\/magazin\/ratgeber\/der-spaziergang-mit-dem-hund\/\"  > Spazierg\u00e4nge<\/a> pro Tag sind ein absolutes Muss. Dies gilt \u00fcbrigens auch, wenn ein gro\u00dfer Garten vorhanden ist. Nat\u00fcrlich kann er sich dort bedingt selbst Bewegung verschaffen. Um dies jedoch auf seinem Niveau zu erreichen, sollte ein weiterer Hund vorhanden sein. Denn gemeinsam k\u00f6nnen sie sich gegenseitig bespa\u00dfen und auspowern. Dies kann einen Spaziergang ersetzen.<\/p>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"background-color:#fefad8\"><strong>Achtung bei der F\u00fctterung:<\/strong> Der Cocker Spaniel ist extrem verfressen. Er wird sich auf alles Fressbare st\u00fcrzen. Dies kann, wenn er k\u00f6rperlich nicht ausgelastet ist, schnell zu Fettleibigkeit werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund seiner Intelligenz ist er sowohl f\u00fcr den Anf\u00e4nger als auch den Profi leicht zu erziehen. Auch seine Anh\u00e4nglichkeit an seine Menschen, sein Rudel hilft, eine gute Bindung, eine gute Sozialisierung herzustellen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der perfekte Mensch f\u00fcr einen English Cocker Spaniel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der perfekte Mensch ist, wenn man sich die Herkunft des Hundes anschaut, ein J\u00e4ger, der aktiv zur Jagd geht und einen gut ausgebildeten Jagdhund an seiner Seite braucht. Leider wird der Cocker Spaniel heute kaum noch von der J\u00e4gerschaft beachtet. Dies ist der Grund daf\u00fcr, weshalb er sich als Begleithund etabliert hat. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gerade in Familien, in denen irgendwie immer jemand zu Hause ist, der sich mit ihm besch\u00e4ftigen kann, ist der Cocker Spaniel sehr gut aufgehoben. Es sollte aber immer bedacht werden, dass dieser Hund ausreichend Bewegung ben\u00f6tigt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Welpen des English Cocker Spaniel kaufen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sie haben Recht \u2013 es ist immer eine Herausforderung, einen seri\u00f6sen Z\u00fcchter zum Kauf eines Welpen zu finden, egal um welche Hunderasse es sich handelt. Und doch ist es immer die beste Option, da man die Zuchtlinie zur\u00fcckverfolgen kann. Auf diese Weise lassen sich auch viele Aufschl\u00fcsse \u00fcber den gesundheitlichen Zustand des Tieres ausmachen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am wichtigsten ist aber, dass man vor der \u00dcbernahme eines Welpen nicht nur zu diesem einen Tier Kontakt aufnehmen kann. Auch der Kontakt zu den Elterntieren und den Geschwistern kann viel zum Verst\u00e4ndnis des (sp\u00e4ter) eigenen Welpen beitragen.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel-welpen.jpg\" loading=\"lazy\" alt=\"English Cocker Spaniel Welpen\" class=\"wp-image-11657\"\/><figcaption>English Cocker Spaniel Welpen | Foto: artush \/ Depositphotos.com<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Erste Ausstattung f\u00fcr den English Cocker Spaniel<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/hundehalsband\/\"  >Hundehalsband<\/a><\/li><li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/hundegeschirr\/\"  >Hundegeschirr<\/a><\/li><li><a href=\"https:\/\/floxik.de\/magazin\/ratgeber\/welche-hundeleine-passt-zu-welchem-zweck\/\"  >Hundeleine<\/a>, zus\u00e4tzlich eventuelle eine <a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/schleppleine\/\"  >Schleppleine<\/a><\/li><li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/hundewassernapf\/\"  >Wasser-<\/a> und <a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/futternapf-hund\/\"  >Futternapf<\/a>, m\u00f6glichst leicht zu reinigen<\/li><li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/hundebett\/\"  >Hundebett<\/a> \/ Decke f\u00fcr den Liegeplatz<\/li><li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/langhaarbuerste-fur-hunde\/\"  >Langhaarb\u00fcrste<\/a><\/li><li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/unterfellbuerste-hund\/\"  >Unterfellb\u00fcrste<\/a><\/li><li><a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/hundekamm\/\"  >Hundekamm<\/a> \/ <a href=\"https:\/\/floxik.de\/magazin\/zubehoer\/laeusekamm-hund\/\"  >L\u00e4usekamm<\/a><\/li><li>Hundefutter<\/li><li>eventuell Spielzeug<\/li><li>eventuell <a href=\"https:\/\/floxik.de\/magazin\/ernaehrung\/hundeleckerli\/\"  >Leckerlis<\/a><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Hundefutter f\u00fcr den English Cocker Spaniel<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es versteht sich von selbst, dass der English Cocker Spaniel hochwertiges Futter ben\u00f6tigt. Aber ACHTUNG \u2013 dieser kleine Hund frisst schneller, als Sie den Napf f\u00fcllen k\u00f6nnen. Daher ist unbedingt auf die korrekte t\u00e4gliche Futtermenge zu achten. Lassen Sie sich nicht dazu verleiten, die Portion zu vergr\u00f6\u00dfern, da sie ja so schnell verschwindet. Der Cocker Spaniel w\u00fcrde nur schnell dick und rund werden. Ist es erst einmal dazu gekommen, ist dieser Fettmantel auch durch starkes Training und vermehrte Bewegung nicht so schnell wieder zu beseitigen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie viel kostet ein English Cocker Spaniel?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der English Cocker Spaniel ist etwas ganz Besonderes. Dies zeigt sich auch im Preis, der f\u00fcr einen Welpen dieser Rasse von einem seri\u00f6sen Z\u00fcchter verlangt wird. Denn hier haben wir es mit einem stolzen Minimalpreis von EURO 1.500 bis 1.600 zu tun. Nach oben hin sind, je nach Zuchtlinie, keine Grenzen gesetzt. Insbesondere seltene Farbgebungen k\u00f6nnen schnell mit \u00fcber EURO 2.000 bewertet werden. Setzen Sie sich also am besten selber ein Limit, das nicht \u00fcberschritten werden sollte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Woher kommt der English Cocker Spaniel?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Name l\u00e4sst es bereits korrekt vermuten: Diese Hunderasse entstammt urspr\u00fcnglich aus England. Er sollte nicht als \u201eder Cocker Spaniel\u201c schlechthin benannt werden. Denn auf der anderen Seite des Ozeans finden wir noch den American Cocker Spaniel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie alt wird der English Cocker Spaniel?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr den English Cocker Spaniel ist ein langes Leben vorgesehen. Die durchschnittliche Lebenserwartung liegt zwischen zw\u00f6lf und vierzehn Jahren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie gro\u00df und schwer wird der English Cocker Spaniel?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Hund wird zu den kleinen bis mittelgro\u00dfen Hunden gez\u00e4hlt. Er erreicht eine Widerristh\u00f6he von rund 40 Zentimetern. Dabei weist er ein Gewicht von knapp 14 Kilogramm auf. R\u00fcden und H\u00fcndinnen weisen keine gro\u00dfen Abweichungen in Bezug auf die Gr\u00f6\u00dfe oder das Gewicht auf.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie viele Welpen bekommt der English Cocker Spaniel?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Da der English Cocker Spaniel zu den kleinen bis mittelgro\u00dfen Hunden geh\u00f6rt, kann von einer durchschnittlichen Wurfgr\u00f6\u00dfe von f\u00fcnf bis acht Welpen ausgegangen werden. Nat\u00fcrlich kann die Anzahl variieren. Grunds\u00e4tzlich aber kann man bei kleineren Hunderassen auch von kleineren W\u00fcrfen ausgehen, als es bei gro\u00dfen Hunden der Fall w\u00e4re.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ist der English Cocker Spaniel ein Jagdhund?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ja, der English Cocker Spaniel ist ein begeisterter und sehr intelligenter J\u00e4ger. Dies f\u00fchrt dazu, dass er bei Spazierg\u00e4ngen nicht von der Leine gelassen werden sollte. Er w\u00fcrde seinem Instinkt folgen und jede F\u00e4hrte untersuchen, die er nur finden kann. Ein Antijagdtraining wird vielfach ausprobiert. Doch sollte man sich nicht zu viele Hoffnungen machen. Der Jagdinstinkt sitzt tief verwurzelt in diesem kleinen Hund. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch heute noch wird er gerne von J\u00e4gern f\u00fcr seinen eigentlichen Zweck, n\u00e4mlich das Jagen, ausgebildet. Und doch sieht man mehr English Cocker Spaniel, die als Begleithund gehalten werden als solche, die tats\u00e4chlich durch die Jagdausbildung gegangen sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wird er von Nicht-J\u00e4gern gehalten, ist dies in seinem eigenen Garten, also seinem Revier, kein Problem. Ein vern\u00fcnftiger, ausbruchsicherer Zaun ist dennoch empfohlen. Dieser sollte auch ein wenig in die Tiefe gehen, da nicht garantiert werden kann, dass er sich nicht darunter hindurch buddeln w\u00fcrde.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ist der English Cocker Spaniel<a> <\/a>ein Familienhund?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Als <a href=\"https:\/\/floxik.de\/magazin\/hunderassen\/familienhunde\/\"  >Familienhund<\/a> ist der English Cocker Spaniel sehr beliebt. Dies verdankt er vermutlich seinem stets fr\u00f6hlichen Wesen. Sie h\u00e4ngen f\u00f6rmlich an ihren Menschen und lieben es,\u00a0 mit ihnen zu spielen oder spazieren zu gehen. Der English Cocker Spaniel geh\u00f6rt zu den kleinen Hunden. Dies und ihre Gutm\u00fctigkeit erm\u00f6glichen es auch etwas gr\u00f6\u00dferen Kindern, mit ihm spazieren zu gehen. Nat\u00fcrlich setzt es eine gute Erziehung und eine sehr gute Anleitung der Kinder voraus. Dann jedoch k\u00f6nnen Hund und Kind zu einem unzertrennlichen Duo zusammenwachsen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eines allerdings gibt es stets zu beachten: Den Jagdtrieb! Dieser Hund sollte, als Vorsichtsma\u00dfnahme, w\u00e4hrend des Spazierganges stets an der Leine gelassen werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Kann der English Cocker Spaniel in einer (Stadt-)wohnung gehalten werden?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Rein von der Gr\u00f6\u00dfe her ist es f\u00fcr den English Cocker Spaniel \u00fcberhaupt kein Problem, das Leben in einer Wohnung zu f\u00fchren. Da er seinen Besitzern \u00fcberall hin folgen w\u00fcrde, wird er sich auch in der Wohnung arrangieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Frage nach dem Leben in der Stadt ist eine andere. Selbstverst\u00e4ndlich kann der English Cocker Spaniel sich den Leben in der Stadt anpassen, solange f\u00fcr ausreichend M\u00f6glichkeiten gesorgt wurde, seinem doch recht ansehnlichen Bewegungsdrang nachzukommen. Allerdings sollte Sie vermeiden, ihn in Menschenmassen mitzunehmen. Bei Einkaufsbummel oder auf den Flohmarkt sollte er nicht mitgenommen werden. Mehr als Beine und viele Geruchseindr\u00fccke w\u00fcrde er nicht geboten bekommen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">FAQ<\/h2>\n\n\n\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Ist der English Cocker Spaniel ein guter Familienhund?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"wp-block-paragraph\">Diese Hunderasse ist ein wunderbarer Familienhund. Er ist ausgeglichen, freundlich, mutig, verspielt, intelligent und kann sich sehr gut auf seine Menschen einstellen, sich an sie anpassen. Die einzige Voraussetzung ist, ihm ausreichend Bewegung zu verschaffen, um ihm ein ausgeglichenes Wesen zu gew\u00e4hrleisten.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Stimmen die Ger\u00fcchte, dass der English Cocker Spaniel ein Jagdhund ist?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"wp-block-paragraph\">Ja, das ist richtig. Urspr\u00fcnglich ist dieser Hund ein Jagdhund, ein St\u00f6berhund, gewesen. Nur selten wird er heute noch von J\u00e4gern ausgebildet und f\u00fcr die Jagd eingesetzt. Dabei ist er von Grund auf ein solider, zuverl\u00e4ssiger Jagdhund.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Es wird gesagt, dass der English Cocker Spaniel auch f\u00fcr Anf\u00e4nger kein Problem darstellt?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"wp-block-paragraph\">Richtig, der English Cocker Spaniel ist sehr intelligent, anh\u00e4nglich und wei\u00df sich an seine Menschen anzupassen. Da er anh\u00e4nglich ist und seine Aufgaben erledigen m\u00f6chte, wird er sich leicht leiten und erziehen lassen. Bei Bedarf kann ein Hundetraining den Menschen bei dieser Aufgabe helfen. Der Hund wird eher wenig Unterst\u00fctzung ben\u00f6tigen.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section\t\thelp class=\"sc_fs_faq sc_card    \"\n\t\t\t\t>\n\t\t\t\t<h3>\ud83d\udc36 Ist der English Cocker Spaniel pflegeleicht?<\/h3>\t\t\t\t<div>\n\t\t\t\t\t\t<div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p class=\"wp-block-paragraph\">Grunds\u00e4tzlich sollte der Cocker aufgrund seines mittellangen Fells jeden zweiten Tag geb\u00fcrstet werden. Ein besonderes Augenmerk ist bei der Pflege auf die Ohren und die Leftzen zu legen, um diese sauber bzw. frei von Verfilzungen zu halten.<\/p>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/section>\n\t\t\n<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\": \"FAQPage\",\n\t\t\"mainEntity\": [\n\t\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Ist der English Cocker Spaniel ein guter Familienhund?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Diese Hunderasse ist ein wunderbarer Familienhund. Er ist ausgeglichen, freundlich, mutig, verspielt, intelligent und kann sich sehr gut auf seine Menschen einstellen, sich an sie anpassen. Die einzige Voraussetzung ist, ihm ausreichend Bewegung zu verschaffen, um ihm ein ausgeglichenes Wesen zu gew\u00e4hrleisten.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Stimmen die Ger\u00fcchte, dass der English Cocker Spaniel ein Jagdhund ist?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Ja, das ist richtig. Urspr\u00fcnglich ist dieser Hund ein Jagdhund, ein St\u00f6berhund, gewesen. Nur selten wird er heute noch von J\u00e4gern ausgebildet und f\u00fcr die Jagd eingesetzt. Dabei ist er von Grund auf ein solider, zuverl\u00e4ssiger Jagdhund.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Es wird gesagt, dass der English Cocker Spaniel auch f\u00fcr Anf\u00e4nger kein Problem darstellt?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Richtig, der English Cocker Spaniel ist sehr intelligent, anh\u00e4nglich und wei\u00df sich an seine Menschen anzupassen. Da er anh\u00e4nglich ist und seine Aufgaben erledigen m\u00f6chte, wird er sich leicht leiten und erziehen lassen. Bei Bedarf kann ein Hundetraining den Menschen bei dieser Aufgabe helfen. Der Hund wird eher wenig Unterst\u00fctzung ben\u00f6tigen.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t,\t\t\t\t{\n\t\t\t\t\"@type\": \"Question\",\n\t\t\t\t\"name\": \"\ud83d\udc36 Ist der English Cocker Spaniel pflegeleicht?\",\n\t\t\t\t\"acceptedAnswer\": {\n\t\t\t\t\t\"@type\": \"Answer\",\n\t\t\t\t\t\"text\": \"<p>Grunds\u00e4tzlich sollte der Cocker aufgrund seines mittellangen Fells jeden zweiten Tag geb\u00fcrstet werden. Ein besonderes Augenmerk ist bei der Pflege auf die Ohren und die Leftzen zu legen, um diese sauber bzw. frei von Verfilzungen zu halten.<\/p>\"\n\t\t\t\t\t\t\t\t\t}\n\t\t\t}\n\t\t\t\t\t\t]\n\t}\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Der English Cocker Spaniel ist uns allen ein Begriff, denn man sieht ihn vielerorts. Ein fr\u00f6hlicher Hund mit lustigen Schlappohren, der sich \u00fcber jeden Menschen&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-2464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hunderassen"],"uagb_featured_image_src":{"full":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel.jpg",825,575,false],"thumbnail":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel-150x150.jpg",150,150,true],"medium":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel-300x209.jpg",300,209,true],"medium_large":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel-768x535.jpg",726,506,true],"large":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel.jpg",726,506,false],"1536x1536":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel.jpg",825,575,false],"2048x2048":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel.jpg",825,575,false],"epcl_classic":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel.jpg",660,460,false],"epcl_fullcover":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/der-english-cocker-spaniel.jpg",825,575,false]},"uagb_author_info":{"display_name":"Floxik Redaktion","author_link":"https:\/\/floxik.de\/magazin\/author\/redaktion\/"},"uagb_comment_info":0,"uagb_excerpt":"Der English Cocker Spaniel ist uns allen ein Begriff, denn man sieht ihn vielerorts. Ein fr\u00f6hlicher Hund mit lustigen Schlappohren, der sich \u00fcber jeden Menschen...","_links":{"self":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts\/2464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/comments?post=2464"}],"version-history":[{"count":1,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts\/2464\/revisions"}],"predecessor-version":[{"id":2466,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts\/2464\/revisions\/2466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/media\/2467"}],"wp:attachment":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/media?parent=2464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/categories?post=2464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/tags?post=2464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}