{"id":664,"date":"2017-06-14T00:00:00","date_gmt":"2017-06-13T22:00:00","guid":{"rendered":"https:\/\/floxik.de\/magazin\/2017\/06\/14\/der-australian-shepard\/"},"modified":"2024-05-31T09:59:36","modified_gmt":"2024-05-31T07:59:36","slug":"der-australian-shepard","status":"publish","type":"post","link":"https:\/\/floxik.de\/magazin\/hunderassen\/der-australian-shepard\/","title":{"rendered":"Der Australian Shepard"},"content":{"rendered":"<div id=\"attachment_2847\" style=\"width: 421px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2847\" class=\"wp-image-2847\" title=\"Australian Shepard\" src=\"https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard.jpg\" loading=\"lazy\" alt=\"Australian Shepard\" width=\"411\" height=\"308\" \/><p id=\"caption-attachment-2847\" class=\"wp-caption-text\">Australian Shepard | Foto: monika1607 \/ pixabay.com<\/p><\/div>\n<p>Der <strong>Australian Shepard<\/strong> ist, obwohl er einer der beliebtesten Hunde Deutschlands ist, immer noch in vielen Bereichen eine vollkommen falsch verstandene Rasse. Diese rein auf besonders ausgepr\u00e4gte Merkmale als H\u00fctehunde gez\u00fcchtete Rasse ist nicht zuletzt auch aufgrund ihrer vielf\u00e4ltigen Farbvarianten ein sehr beliebter Familienhund. Leider sehen viele Hundebesitzer nicht ein, dass es bei dieser Rasse in erster Linie sehr auf die entsprechende Auslastung der Tiere ankommt. Sie brauchen nicht nur jede Menge Auslauf sondern schlichtweg eine Aufgabe. Bei dieser muss nat\u00fcrlich auch die geistige Auslastung des Hundes gegeben sein. F\u00fchlt sich der Australian Shepard gelangweilt weil er zu wenig Auslastung hat, dann kann es schnell passieren, dass er sich seine eigene Besch\u00e4ftigung sucht. Diese liegt allerdings in den meisten F\u00e4llen nicht im Interesse des Besitzers. Dem Arbeiten mit diesen Hunden kommt ihre hohe Intelligenz zu Gute. Doch genau diese hohe Intelligenz f\u00fchrt auch nur allzu oft dazu, dass der Australian Shepard, wenn er sich langweilt beginnt, eigene Entscheidungen zu treffen. Hier liegt die Kunst des Hundebesitzers darin, diesem entgegenzuwirken indem er seinen Hund entsprechend auslastet, f\u00f6rdert und fordert.<\/p><div id=\"floxi-3264706385\" class=\"floxi-chatbot floxi-entity-placement\" style=\"margin-left: auto;margin-right: auto;text-align: center;\">    <iframe\r\n      data-chat-frame=\"11ef639c-7b4d-f7d0-8a5a-d790f206031e\"\r\n      width=\"550\"\r\n      height=\"700\"\r\n      style=\"border:0;background:white;border: 1px solid lightgrey;border-radius: 10px;padding:15px;\"\r\n\t\t\t\r\n    ><\/iframe>\r\n    <script\r\n      src=\"https:\/\/retune.so\/api\/script\/chat.js?iframe&id=11ef639c-7b4d-f7d0-8a5a-d790f206031e\"\r\n      defer\r\n    ><\/script>\r\n    <\/div>\n<h2>Der Australian Shepard und sein Wesen<\/h2>\n<p>Das Wesen des Australian Shepard l\u00e4sst sich in wenigen Worten beschreiben. Er ist sehr sportlich, aufmerksam und h\u00f6chst intelligent. Diese Eigenschaften paaren sich beim Australian Shepard mit einem gesunden Wachinstinkt und einem enormen Lernverm\u00f6gen. Dennoch ist diese Rasse sehr liebevoll und eignet sich bei entsprechender Auslastung durchaus auch als Familienhund. Allerdings m\u00f6chten diese Hunde nicht einfach nur bewegt werden, sie m\u00f6chten auch ihre h\u00fcbschen K\u00f6pfe anstrengen. Daf\u00fcr eignet sich die F\u00e4hrtenarbeit mindestens ebenso gut wie der Hundesport, bei dem sich der Hund sowohl bewegen als auch viel konzentrieren muss. Doch auch beim Erlernen diverser Tricks und Kunstst\u00fccke beweisen diese intelligenten Hunde, dass sie ebenso lernwillig wie auch lernf\u00e4hig sind. \u00a0Sie lieben es zu arbeiten und sich zu pr\u00e4sentieren. Zu unterscheiden ist beim Australian Shepard heutzutage jedoch zuchtbedingt auch zwischen der reinen Arbeitslinie und der etwas weniger arbeitlich gepr\u00e4gten Showlinie. Wobei nat\u00fcrlich auch letztere Zuchten immer noch einen gewissen Anspruch an das Arbeiten in k\u00f6rperlicher wie auch in geistiger Hinsicht haben. Alles in allem ist der Australian Shepard ein treuer und liebevoller Begleiter, der jedoch die Arbeit braucht um sich wohlf\u00fchlen zu k\u00f6nnen und gl\u00fccklich zu sein.<\/p>\n<h2>Der geschichtliche Hintergrund vom Australian Shepard<\/h2>\n<p>Anders als es der Name dieser Rasse vielleicht vermuten l\u00e4sst, liegt der Ursprung in Nordamerika und nicht in Australien. Jedoch wird sein Ursprung auch mit baskischen Sch\u00e4fern in Verbindung gebracht, die um das 19. Jahrhundert von Australien aus nach Amerika einwanderten und dabei eine Vielzahl von Merinoschafen bei sich hatten. Diese Schafe wurden weit vor dieser Zeit bereits von Amerika aus nach Australien exportiert und bekamen aus diesem Grund auch den Namen Australian Sheep. Und eben jene Schafe waren es, die nun viele Jahre sp\u00e4ter gemeinsam mit ihren Sch\u00e4fern wieder nach Nordamerika zur\u00fcckkamen. Um dem Schutz und der Bewachung der Tiere gerecht werden zu k\u00f6nnen, wurden mutige Hunde ben\u00f6tigt, die gelehrig, wenig und schnell waren und dennoch eine unbedingte Liebe zum Menschen hatten. Eben die Australian Shepards. In Arizona wurde im Jahre 1957 das erste Zuchtbuch f\u00fcr diese Rasse er\u00f6ffnet, eine Anerkennung durch die FCI erfolgte erst viele Jahre sp\u00e4ter, n\u00e4mlich 1996. Welche urspr\u00fcnglichen Rassen und Hundetypen der Herauszucht vom Australian Shepard zugrunde liegen, dar\u00fcber herrscht noch keine weitreichende Kenntnis. Fest steht jedoch, dass die gezielte Zucht auf die heute vertretene Farbvielfalt erst im Laufe der Jahre zutage trat. Doch diese ganz gezielte Zucht auf verschiedene Farbschl\u00e4ge brachte auch einige gravierende gesundheitliche Defekte mit sich, auf die wir sp\u00e4ter noch zu sprechen kommen.<\/p>\n<h2>Der Australian Shepard und seine Anspr\u00fcche<\/h2>\n<p>Der Australian Shepard wurde eigens als H\u00fctehund gez\u00fcchtet und hat demzufolge auch heute noch, ganz gleich aus welcher Linie er letzten Endes stammt, ein gewisses H\u00fctegen in sich. Das hei\u00dft, er ist zwar durchaus ein treuer Begleiter und liebevoller Familienhund, doch er m\u00f6chte eine Aufgabe haben. Eine Aufgabe, die ihn auslastet und die ihn sowohl geistig als auch k\u00f6rperlich f\u00f6rdert und fordert.\u00a0 Neben dem t\u00e4glichen Auslauf, auf den er keinesfalls verzichten kann sollte er also auch geistig ausgelastet werden. Ob dies nun im Rahmen von F\u00e4hrtensuche oder dem Erlernen zahlreicher Tricks und Kunstst\u00fccke oder doch eher im sportlichen Bereich passiert ist einerlei. Wichtig ist, dass dieser Hund keine Langeweile hat. Dann n\u00e4mlich sucht er sich eigenm\u00e4chtig eine Besch\u00e4ftigung und die wird dem Besitzer in den meisten F\u00e4llen sicher nicht gefallen. Obgleich mit einem stattlichen Arbeitstrieb versehen, m\u00f6chte der Australian Shepard dennoch am liebsten auch einen vollwertigen Familienanschluss genie\u00dfen. Er ist ein absoluter Schmuser, was bei der Beurteilung vom Zeitfaktor in jedem Fall Ber\u00fccksichtigung finden sollte. Auch in Sachen Fellpflege sollte hier die entsprechende Zeit mit eingerechnet werden. Der Australian Shepard verf\u00fcgt \u00fcber ein dichtes Fell mit Unterwolle, das regelm\u00e4\u00dfiger Pflege bedarf.<\/p>\n<h2>Der Australian Shepard und seine Gesundheit<\/h2>\n<div id=\"attachment_2846\" style=\"width: 382px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2846\" class=\"wp-image-2846\" title=\"Australian Shepard Welpen\" src=\"https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard-Welpen.jpg\" loading=\"lazy\" alt=\"Australian Shepard Welpen\" width=\"372\" height=\"279\" \/><p id=\"caption-attachment-2846\" class=\"wp-caption-text\">Australian Shepard Welpen | Foto: monika1607 \/ pixabay.com<\/p><\/div>\n<p>Wie bereits weiter oben erw\u00e4hnt, tr\u00e4gt der Australian Shepard aufgrund der zwischenzeitlich stark auf Farbe ausgelegten Zucht eine Reihe an m\u00f6glichen Erkrankungen mit sich rum. Neben den klassischen genetisch bedingten Erkrankungen im Bereich von HD und ED sind hier vor allem beim Farbschlag Blue Merle die Augen betroffen, ebenso die Ohren. Bei Verpaarungen aus zwei Blue Merle Eltern kann davon ausgegangen werden, dass der \u00fcberwiegende Teil der Nachzuchten mit Blindheit und Taubheit zu k\u00e4mpfen haben. Doch auch im Bereich MDR 1, also einer sogenannten Arzneimittelunvertr\u00e4glichkeit die sich in erster Linie auf den Wirkstoff Ivermectine bezieht, ist der Australian Shepard sehr anf\u00e4llig. Daneben sind jedoch auch immer wieder Allergien, Probleme im Bereich des Herzens und der Schilddr\u00fcse sowie Gebissfehler festzustellen. Ein Problem, das sicherlich auch auf die recht wilde Vermehrung zur\u00fcckzuf\u00fchren ist, die auftrat als der gro\u00dfe Boom auf diese Hunde entstand.\u00a0 Es ist beim Kauf eines Australian Shepard unbedingt und in jedem Fall darauf zu achten, dass dieser aus einer verantwortungsvollen Zucht kommt, bei der auch alle Elterntiere auf die diversen Erbkrankheiten negativ getestet wurden.<\/p>\n<h2>Der perfekte Mensch f\u00fcr einen Australian Shepard ist\u2026..<\/h2>\n<p>Sehr sportlich und gerne in der Natur unterwegs. Er hat die M\u00f6glichkeit, sich hinreichend den Belangen seines Hundes zu widmen und schreckt auch vor der Fellpflege nicht zur\u00fcck. Da es sich beim Australian Shepard um einen ganz besonders intelligenten Hund handelt, ist er f\u00fcr reine Anf\u00e4nger nur bedingt geeignet und hier sollte dann bei der Erziehung in jedem Fall auch mit professioneller Hilfe zu Werke gegangen werden. Auch sollte der Besitzer eines Australian Shepard in jedem Fall sehr kreativ sein um seinem Hund auch eine gewisse Abwechslung bei der Arbeit und der Besch\u00e4ftigung bieten zu k\u00f6nnen. Dies ist vor allem auch f\u00fcr das geistige Wohlbefinden dieser Hunde von besonderer Wichtigkeit. Ansonsten muss nat\u00fcrlich neben viel Bewegung in der Natur und der Arbeit selber auch viel gekuschelt werden. Auch diese Arbeitshunde brauchen ihre Streicheleinheiten und eine liebevolle Umgebung.\u00a0 Kinder sind sehr willkommen, auf diese kann der Australian Shepard n\u00e4mlich aufpassen, kann sie umsorgen und sie bespa\u00dfen. Somit ist er nat\u00fcrlich auch als Familienhund bestens geeignet, wenn denn die Rahmenbedingungen in punkto Auslastung stimmen.<\/p><div id=\"floxi-115595473\" class=\"floxi-inhalt floxi-entity-placement\">\n<div class=\"aawp\">\n\n            \n            \n<div class=\"aawp-product aawp-product--horizontal aawp-product--css-adjust-image-large\"  data-aawp-product-id=\"B01MSHEXVC\" data-aawp-product-title=\"FABCARE Laser Hornhautraspel Set  5-teilig  Neue verbesserte Version Austauschbare Raspelfl\u00e4che - Hornhautentferner inkl Mini Fu\u00dffeile Fu\u00dfpflege Set zur Hornhaut Entfernung Hornhautfeile\">\n\n    \n    <div class=\"aawp-product__thumb\">\n        <a class=\"aawp-product__image-link\"\n           href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"UNSER TIPP: ANIFIT Nassfutter\" rel=\"nofollow\" target=\"_blank\">\n            <img decoding=\"async\" class=\"aawp-product__image\" src=\"https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/07\/Hund-200g-Dosen_w960_h960_q90_jpg.jpg\" alt=\"UNSER TIPP: ANIFIT Nassfutter\"  \/>\n        <\/a>\n\n                    <div class=\"aawp-product__rating\">\n                <a class=\"aawp-star-rating aawp-star-rating--medium aawp-star-rating--v2\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"Bewertungen auf Amazon\" rel=\"nofollow\" target=\"_blank\"><span style=\"width: 100%;\"><\/span><\/a>\n                            <\/div>\n            <\/div>\n\n    <div class=\"aawp-product__content\">\n        <a class=\"aawp-product__title\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"UNSER TIPP: ANIFIT Nassfutter\" rel=\"nofollow\" target=\"_blank\">\n            UNSER TIPP: ANIFIT Nassfutter         <\/a>\n        <div class=\"aawp-product__description\">\n            <b>\u25b7 Hoher Fleischanteil<br>\r\n\u25b7 Premium-Qualit\u00e4t der Zutaten <br>\r\n\u25b7 Frei von Tierversuchen <br>\r\n<br><\/b>\r\nANIFIT Nassfutter f\u00fcr Hunde ist ein hochwertiges Futter mit einem hohen Fleischanteil und Zutaten in Premium-Qualit\u00e4t. Es ist frei von k\u00fcnstlichen Zusatzstoffen und wird ohne Tierversuche hergestellt, was es zu einer gesunden und ethischen Wahl f\u00fcr die Ern\u00e4hrung Ihres Hundes macht.\r\n<br><br><b>10% F\u00dcR NEUKUNDEN<br>\r\n\u27a5 Gutscheincode: LEX10<br><\/b>\r\n        <\/div>\n    <\/div>\n\n    <div class=\"aawp-product__footer\">\n\n        <div class=\"aawp-product__pricing\">\n            \n                            <span class=\"aawp-product__price aawp-product__price--current\">ab 31,40 \u20ac<\/span>\n            \n                    <\/div>\n\n                <a class=\"aawp-button aawp-button--buy aawp-button aawp-button--blue rounded shadow\" href=\"https:\/\/floxik.de\/magazin\/go\/nassfutter\" title=\"Probierpaket Anifit anfordern \u00bb\" target=\"_blank\" rel=\"nofollow\">Probierpaket Anifit anfordern \u00bb<\/a>\n            <\/div>\n\n<\/div>\n\n    \n<\/div>\n<\/div>\n<h2>Fazit<\/h2>\n<p>Wer sich diese tollen Hunde ins Haus holt, der sollte sich im Vorfeld in jedem Fall besonders intensiv mit den W\u00fcnschen und Bed\u00fcrfnissen befassen. Stimmt das Umfeld f\u00fcr einen Australian Shepard so kann man mit ihm durch dick und d\u00fcnn gehen. Immer eng an der Seite seines Menschen ist dieser tolle Hund f\u00fcr jedes Abenteuer zu haben und begleitet seinen Menschen treu ergeben, wo immer dieser auch hingeht. Allerdings ist diese Rasse recht anspruchsvoll und als Anf\u00e4nger sollte man hier zumindest anf\u00e4nglich mit fachm\u00e4nnischer Unterst\u00fctzung arbeiten. Sind die Grundsteine jedoch gelegt, dann hat man mit einem Australian Shepard einen optimalen Familienhund, der gl\u00fccklich ist sein neues Rudel bewachen, begleiten und besch\u00fctzen zu d\u00fcrfen. Daneben darf sich jeder Besitzer dieser Hunde sicher sein, dass er immer wieder die eine oder andere Situation mit seinem Vierbeiner erleben wird, die ihn zum Lachen bringt und in Erstaunen versetzt.<\/p>\n<p>Mehr Informationen rund um den Australian Shepard findet man auf <a href=\"https:\/\/www.myaustralianshepherd.de\/\" rel=\"nofollow noopener\" target=\"_blank\">myaustralianshepherd.de<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Australian Shepard ist, obwohl er einer der beliebtesten Hunde Deutschlands ist, immer noch in vielen Bereichen eine vollkommen falsch verstandene Rasse. Diese rein auf&#8230;<\/p>\n","protected":false},"author":3,"featured_media":665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hunderassen"],"uagb_featured_image_src":{"full":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard.jpg",640,480,false],"thumbnail":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard-150x150.jpg",150,150,true],"medium":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard-300x225.jpg",300,225,true],"medium_large":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard.jpg",640,480,false],"large":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard.jpg",640,480,false],"1536x1536":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard.jpg",640,480,false],"2048x2048":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard.jpg",640,480,false],"epcl_classic":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard.jpg",640,480,false],"epcl_fullcover":["https:\/\/floxik.de\/magazin\/wp-content\/uploads\/2024\/05\/Australien-Shepard.jpg",640,480,false]},"uagb_author_info":{"display_name":"Floxik Redaktion","author_link":"https:\/\/floxik.de\/magazin\/author\/redaktion\/"},"uagb_comment_info":0,"uagb_excerpt":"Der Australian Shepard ist, obwohl er einer der beliebtesten Hunde Deutschlands ist, immer noch in vielen Bereichen eine vollkommen falsch verstandene Rasse. Diese rein auf...","_links":{"self":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts\/664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/comments?post=664"}],"version-history":[{"count":1,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts\/664\/revisions"}],"predecessor-version":[{"id":667,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/posts\/664\/revisions\/667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/media\/665"}],"wp:attachment":[{"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/media?parent=664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/categories?post=664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/floxik.de\/magazin\/wp-json\/wp\/v2\/tags?post=664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}